{"id":22025,"date":"2025-02-17T17:20:28","date_gmt":"2025-02-17T15:20:28","guid":{"rendered":"https:\/\/retrobat.cat\/agenda\/mediumnidad-encuentro-presencial-grupal\/"},"modified":"2025-02-19T21:53:08","modified_gmt":"2025-02-19T19:53:08","slug":"mediumnidad-encuentro-presencial-grupal","status":"publish","type":"project","link":"https:\/\/retrobat.cat\/es\/agenda\/mediumnidad-encuentro-presencial-grupal\/","title":{"rendered":"Mediumnidad. Encuentro presencial grupal."},"content":{"rendered":"\n<p><strong>PROFESIONAL: <\/strong>Sonia Talabante Luis<br\/><strong>FECHA:<\/strong> Martes, 4 marzo 2025<\/p>\n\n<p><strong>HORARIO<\/strong>: De 18\u202fh a 21\u202fh<br\/><strong>PRECIO: <\/strong>20\u202f\u20ac (como representante) o 100\u20ac (para trabajar asunto personal)<br\/><strong>MODALIDAD: <\/strong>Presencial<br\/><strong>TIPOLOG\u00cdA DE PLAZAS:<\/strong><\/p>\n\n<p>Guiada por <strong>Sonia Talabante Luis<\/strong>, junto con dos profesionales m\u00e1s, este encuentro est\u00e1 pensado para:<\/p>\n\n<p>\u2705Aportar informaci\u00f3n que ayude a comprender mejor la mediumnidad, invitando a los participantes a expresar sus dudas e inquietudes, tanto personales como profesionales, sobre esta tem\u00e1tica.<\/p>\n\n<p>\u2705 Ofrecer un espacio en el que, aunque no se buscar\u00e1n canalizaciones a petici\u00f3n de los asistentes, es muy posible que \u00e9stas se manifiesten de forma natural, como invitaciones desde una dimensi\u00f3n espiritual dirigidas a alguno de los presentes.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/retrobat.cat\/producte\/mediumnitat-sense-filtres-secrets-i-mentides\/\">M\u00c1S INFO<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/retrobat.cat\/producte\/mediumnitat-sense-filtres-secrets-i-mentides\/\" target=\"_blank\" rel=\"noreferrer noopener\">RESERVA<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>4 mar. 2025<\/p>\n","protected":false},"author":2,"featured_media":21992,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[218,291],"project_tag":[],"class_list":["post-22025","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-constellacions-familiars-es","project_category-humanista-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project\/22025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/comments?post=22025"}],"version-history":[{"count":1,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project\/22025\/revisions"}],"predecessor-version":[{"id":22026,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project\/22025\/revisions\/22026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/media\/21992"}],"wp:attachment":[{"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/media?parent=22025"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project_category?post=22025"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/retrobat.cat\/es\/wp-json\/wp\/v2\/project_tag?post=22025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}